{"id":391,"date":"2021-06-09T06:00:17","date_gmt":"2021-06-09T09:00:17","guid":{"rendered":"http:\/\/vgeducacional.com\/blog\/?p=391"},"modified":"2021-06-08T18:16:51","modified_gmt":"2021-06-08T21:16:51","slug":"arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles","status":"publish","type":"post","link":"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/","title":{"rendered":"Arquivos: que import\u00e2ncia possuem e por que dedicamos um dia a eles"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-402\" src=\"http:\/\/vgeducacional.com\/blog\/wp-content\/uploads\/2021\/06\/aaaaaaa-1024x599.jpg\" alt=\"\" width=\"525\" height=\"307\" srcset=\"https:\/\/vgeducacional.com\/blog\/wp-content\/uploads\/2021\/06\/aaaaaaa-1024x599.jpg 1024w, https:\/\/vgeducacional.com\/blog\/wp-content\/uploads\/2021\/06\/aaaaaaa-300x175.jpg 300w, https:\/\/vgeducacional.com\/blog\/wp-content\/uploads\/2021\/06\/aaaaaaa-768x449.jpg 768w, https:\/\/vgeducacional.com\/blog\/wp-content\/uploads\/2021\/06\/aaaaaaa.jpg 1920w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">No dia 9 de junho, comemoramos um dia pouco conhecido, mas muito importante: o Dia Internacional dos Arquivos. Em 9 de junho de 1948, a Unesco criou o Conselho Internacional de Arquivos, ent\u00e3o, desde 2007, esse dia foi escolhido para promover a reflex\u00e3o e o di\u00e1logo sobre a import\u00e2ncia dos arquivos em nossas vidas.<\/span><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Os arquivos e os documentos nem sempre estiveram armazenados em pastas em nossos computadores, hospedados em servidores com f\u00e1cil acesso pela internet ou empilhados em caixas. Mas eles sempre foram utilizados para documentar fatos, provar algo, firmar acordos, divulgar e registrar acontecimentos e, obviamente, sempre foram ferramentas de gest\u00e3o para o Estado. Isso tudo, com certeza, remonta a muitos s\u00e9culos antes do nosso uso <\/span><i><span style=\"font-weight: 400;\">on-line<\/span><\/i><span style=\"font-weight: 400;\"> dos arquivos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Hoje em dia, quando pensamos na fun\u00e7\u00e3o dos arquivos, devemos considerar que eles n\u00e3o s\u00e3o apenas para os usos j\u00e1 citados. Algo fundamental que os documentos e os arquivos registram s\u00e3o as hist\u00f3rias dos povos. A partir do s\u00e9culo XVIII, os arquivos come\u00e7aram a ser utilizados para estudar as culturas e para compreender o passado destas e se mostram, at\u00e9 hoje, fontes confi\u00e1veis. A oralidade e a arte desempenham pap\u00e9is fundamentais para a compreens\u00e3o das culturas, mas algumas informa\u00e7\u00f5es s\u00f3 podem ser encontradas por meio de documentos e arquivos. Por exemplo, como era o funcionamento de institui\u00e7\u00f5es p\u00fablicas e empresas, como aconteciam os neg\u00f3cios e os acordos em cada regi\u00e3o. Tudo isso se encontra nesses arquivos. Mas o mais interessante \u00e9 que n\u00e3o \u00e9 s\u00f3 a vida p\u00fablica que pode ser analisada por meio de arquivos e documentos, mas tamb\u00e9m a vida privada de indiv\u00edduos ou grupos sociais.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Dessa forma, \u00e9 interessante pensarmos em como os arquivos j\u00e1 influenciam a maneira de vivenciarmos nossas pr\u00f3prias vidas. Temos registros desde antes do nosso nascimento. Com formul\u00e1rios e documentos, podemos ter todo o nosso hist\u00f3rico de vida marcado em folhas de papel ou em c\u00f3digos em computadores. Com os arquivos, podemos descobrir sobre nossos antepassados e, tamb\u00e9m, conhecer a cultura de nossos povos. Mas \u00e9 importante lembrarmos que a deten\u00e7\u00e3o de certas informa\u00e7\u00f5es pode pertencer a pessoas ou Estados que n\u00e3o pretendem registrar aquele per\u00edodo, e isso, infelizmente, promove o apagamento de gera\u00e7\u00f5es de hist\u00f3ria, assim como se viu acontecer com o povo da \u00c1frica, que foi escravizado e perdeu todos os seus documentos e registros ap\u00f3s os governantes decidirem apagar as provas de uma na\u00e7\u00e3o escravocrata. Assim, at\u00e9 mesmo os sobrenomes dos povos negros se perderam e, tamb\u00e9m, muitas das hist\u00f3rias que esses arquivos poderiam contar para n\u00f3s.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Como destaca a autora Chimamanda Ngozi Adichie (2009), em \u201cO perigo da hist\u00f3ria \u00fanica\u201d, \u00e9 muito f\u00e1cil contarmos sempre a mesma hist\u00f3ria e assumirmos que esta \u00e9 a \u00fanica vers\u00e3o dos fatos, mas precisamos lembrar que os arquivos podem ser uma excelente ferramenta para entendermos todos os lados de uma narrativa. Os arquivos nos servem de prova, contam hist\u00f3rias e constroem narrativas e identidades, resgatam mem\u00f3rias e nos ajudam a gerir nossas vidas de uma maneira mais organizada. Por isso, podemos come\u00e7ar a pensar melhor sobre o que faremos com os nossos arquivos, talvez jog\u00e1-los fora n\u00e3o seja t\u00e3o interessante para quem viver\u00e1 depois da gente. Da mesma forma, podemos encontrar, em todas as caixas cheias de coisas nos nossos pais e av\u00f3s, hist\u00f3rias incr\u00edveis e nunca ouvidas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Refer\u00eancias<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">ADICHIE, C. N. O perigo da hist\u00f3ria \u00fanica. <\/span><b>TEDGlobal<\/b><span style=\"font-weight: 400;\">, 2009. Dispon\u00edvel em: <\/span><a href=\"https:\/\/www.ted.com\/talks\/chimamanda_ngozi_adichie_the_danger_of_a_single_story\/transcript?language=pt\"><span style=\"font-weight: 400;\">https:\/\/www.ted.com\/talks\/chimamanda_ngozi_adichie_the_danger_of_a_single_story\/transcript?language=pt<\/span><\/a><span style=\"font-weight: 400;\">. Acesso em: 4 jun. 2021.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">TOGNOLI, N. B. Por que celebrar o Dia Internacional dos Arquivos? <\/span><b>Unespci\u00eancia<\/b><span style=\"font-weight: 400;\">, 2016. Dispon\u00edvel em: <\/span><a href=\"http:\/\/unespciencia.com.br\/2016\/07\/01\/arquivologia\/\"><span style=\"font-weight: 400;\">http:\/\/unespciencia.com.br\/2016\/07\/01\/arquivologia\/<\/span><\/a><span style=\"font-weight: 400;\">. Acesso em: 4 jun. 2021.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 9 de junho, comemoramos um dia pouco conhecido, mas muito importante: o Dia Internacional dos Arquivos. Em 9 de junho de 1948, a Unesco criou o Conselho Internacional de Arquivos, ent\u00e3o, desde 2007, esse dia foi escolhido para promover a reflex\u00e3o e o di\u00e1logo sobre a import\u00e2ncia dos arquivos em nossas vidas.<\/p>\n","protected":false},"author":2,"featured_media":401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivos: que import\u00e2ncia possuem e por que dedicamos um dia a eles -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos: que import\u00e2ncia possuem e por que dedicamos um dia a eles -\" \/>\n<meta property=\"og:description\" content=\"No dia 9 de junho, comemoramos um dia pouco conhecido, mas muito importante: o Dia Internacional dos Arquivos. Em 9 de junho de 1948, a Unesco criou o Conselho Internacional de Arquivos, ent\u00e3o, desde 2007, esse dia foi escolhido para promover a reflex\u00e3o e o di\u00e1logo sobre a import\u00e2ncia dos arquivos em nossas vidas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T09:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-08T21:16:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vgeducacional.com\/blog\/wp-content\/uploads\/2021\/06\/aaaaaaa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Clau Henrique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clau Henrique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/\",\"url\":\"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/\",\"name\":\"Arquivos: que import\u00e2ncia possuem e por que dedicamos um dia a eles -\",\"isPartOf\":{\"@id\":\"http:\/\/vgeducacional.com\/blog\/#website\"},\"datePublished\":\"2021-06-09T09:00:17+00:00\",\"dateModified\":\"2021-06-08T21:16:51+00:00\",\"author\":{\"@id\":\"http:\/\/vgeducacional.com\/blog\/#\/schema\/person\/a7c1cb41e115735407cac97a854ebb0e\"},\"breadcrumb\":{\"@id\":\"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/vgeducacional.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arquivos: que import\u00e2ncia possuem e por que dedicamos um dia a eles\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/vgeducacional.com\/blog\/#website\",\"url\":\"http:\/\/vgeducacional.com\/blog\/\",\"name\":\"\",\"description\":\"VG Educacional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/vgeducacional.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/vgeducacional.com\/blog\/#\/schema\/person\/a7c1cb41e115735407cac97a854ebb0e\",\"name\":\"Clau Henrique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/vgeducacional.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a9ac12b2747ecb98694bd7f5fe153525?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a9ac12b2747ecb98694bd7f5fe153525?s=96&d=mm&r=g\",\"caption\":\"Clau Henrique\"},\"url\":\"https:\/\/vgeducacional.com\/blog\/author\/clau-henriquevgeducacional-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos: que import\u00e2ncia possuem e por que dedicamos um dia a eles -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos: que import\u00e2ncia possuem e por que dedicamos um dia a eles -","og_description":"No dia 9 de junho, comemoramos um dia pouco conhecido, mas muito importante: o Dia Internacional dos Arquivos. Em 9 de junho de 1948, a Unesco criou o Conselho Internacional de Arquivos, ent\u00e3o, desde 2007, esse dia foi escolhido para promover a reflex\u00e3o e o di\u00e1logo sobre a import\u00e2ncia dos arquivos em nossas vidas.","og_url":"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/","article_published_time":"2021-06-09T09:00:17+00:00","article_modified_time":"2021-06-08T21:16:51+00:00","og_image":[{"url":"https:\/\/vgeducacional.com\/blog\/wp-content\/uploads\/2021\/06\/aaaaaaa.png","width":1,"height":1,"type":"image\/png"}],"author":"Clau Henrique","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Clau Henrique","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/","url":"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/","name":"Arquivos: que import\u00e2ncia possuem e por que dedicamos um dia a eles -","isPartOf":{"@id":"http:\/\/vgeducacional.com\/blog\/#website"},"datePublished":"2021-06-09T09:00:17+00:00","dateModified":"2021-06-08T21:16:51+00:00","author":{"@id":"http:\/\/vgeducacional.com\/blog\/#\/schema\/person\/a7c1cb41e115735407cac97a854ebb0e"},"breadcrumb":{"@id":"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vgeducacional.com\/blog\/2021\/06\/09\/arquivos-que-importancia-possuem-e-por-que-dedicamos-um-dia-a-eles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/vgeducacional.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Arquivos: que import\u00e2ncia possuem e por que dedicamos um dia a eles"}]},{"@type":"WebSite","@id":"http:\/\/vgeducacional.com\/blog\/#website","url":"http:\/\/vgeducacional.com\/blog\/","name":"","description":"VG Educacional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vgeducacional.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"http:\/\/vgeducacional.com\/blog\/#\/schema\/person\/a7c1cb41e115735407cac97a854ebb0e","name":"Clau Henrique","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/vgeducacional.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a9ac12b2747ecb98694bd7f5fe153525?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a9ac12b2747ecb98694bd7f5fe153525?s=96&d=mm&r=g","caption":"Clau Henrique"},"url":"https:\/\/vgeducacional.com\/blog\/author\/clau-henriquevgeducacional-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/posts\/391"}],"collection":[{"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/comments?post=391"}],"version-history":[{"count":4,"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/posts\/391\/revisions"}],"predecessor-version":[{"id":404,"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/posts\/391\/revisions\/404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/media\/401"}],"wp:attachment":[{"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/media?parent=391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/categories?post=391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vgeducacional.com\/blog\/wp-json\/wp\/v2\/tags?post=391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}